{"id":15220,"date":"2023-06-01T18:34:00","date_gmt":"2023-06-01T16:34:00","guid":{"rendered":"https:\/\/francelyme.fr\/site\/?p=15220"},"modified":"2025-11-29T22:56:56","modified_gmt":"2025-11-29T21:56:56","slug":"editorial-de-juin-2023","status":"publish","type":"post","link":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/","title":{"rendered":"\u00c9ditorial de juin 2023"},"content":{"rendered":"<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n<div id=\"fb-root\"><\/div>\n<p>Cher(e) Ami(e), Cher(e) Membre, Cher(e) Soutien,<\/p>\n<p><strong>L\u2019actualit\u00e9 internationale<\/strong><\/p>\n<p>Le \u2018Lyme Protest\u2019 du mois de mai a \u00e9t\u00e9 prolifique aux Etats-Unis, avec beaucoup d\u2019\u00e9v\u00e9nements, de conf\u00e9rences, de communication sur les r\u00e9seaux et dans les m\u00e9dias. Je voudrais revenir sur deux d\u2019entre eux, qui m\u2019ont particuli\u00e8rement int\u00e9ress\u00e9.<\/p>\n<p>Tout d\u2019abord, le film \u00ab The Quiet Epidemic \u00bb (l\u2019\u00e9pid\u00e9mie silencieuse), sorti le 16 mai sur les plateformes. Pour moi, ce film est un vrai \u00e9v\u00e9nement dans le paysage Lyme. Il fait un point clair et complet sur la maladie, depuis ses origines jusqu\u2019\u00e0 nos jours, dans une forme tr\u00e8s accessible au grand public. M\u00eame si dans l\u2019imm\u00e9diat, il n\u2019est disponible qu\u2019en version anglaise. Pour info, je l\u2019ai trouv\u00e9 sur la plateforme Vimeo, avec la possibilit\u00e9 d\u2019avoir les sous-titres en anglais, \u00e7a aide quand m\u00eame\u2026 Le film d\u00e9taille la controverse, avec beaucoup de t\u00e9moignages de malades, de m\u00e9decins, de scientifiques et de responsables sanitaires, en mettant en lumi\u00e8re les conflits d\u2019int\u00e9r\u00eats en jeu sur ce dossier. Les chercheurs des plus grandes universit\u00e9s am\u00e9ricaines qui s\u2019y expriment apportent de nombreux \u00e9l\u00e9ments prouvant la persistance de la bact\u00e9rie, et l\u2019existence de la forme chronique de l\u2019infection.<\/p>\n<p>Ensuite la conf\u00e9rence du Dr John Aucott, de l\u2019Universit\u00e9 Johns Hopkins, intitul\u00e9e \u00ab Advances in Lyme Disease and Tickborne Disease Research \u00bb (avanc\u00e9es de la recherche sur la maladie de Lyme et les autres MVT, acc\u00e8s sur le site Lymedisease.org). John Aucott revient sur les derni\u00e8res d\u00e9couvertes de la recherche, en particulier sur les preuves concernant le manque de fiabilit\u00e9 des tests Elisa et Western Blot, sur les preuves fournies \u00e0 pr\u00e9sent par l\u2019imagerie de la persistance de l\u2019inflammation neurologique c\u00e9r\u00e9brale (\u00e0 l\u2019origine de nombreux sympt\u00f4mes : brouillard mental, difficult\u00e9 de concentration, perte de m\u00e9moire, grande fatigue, troubles du sommeil, anxi\u00e9t\u00e9, d\u00e9pression, etc.). Il revient sur l\u2019\u00e9tude de 2022 montrant que 14 % des patients trait\u00e9s initialement pour l\u2019infection d\u00e9veloppent effectivement la forme persistante de la maladie. Il pr\u00e9sente \u00e9galement les nombreux points communs avec le Covid long et d\u2019autres infections chroniques, ouvrant de nouvelles pistes de recherche. John Aucott pr\u00e9sente enfin, et surtout, les travaux en cours pour disposer de nouveaux tests fiables, et deux nouvelles pistes de traitement : un antibiotique (la t\u00e9tracycline), et un hallucinog\u00e8ne (la psylocybine), dont les propri\u00e9t\u00e9s anti-inflammatoires sur le syst\u00e8me nerveux central pourraient apporter une aide d\u00e9cisive pour am\u00e9liorer la qualit\u00e9 de vie et la sant\u00e9 des patients. Des tests cliniques sont d\u00e9j\u00e0 engag\u00e9s pour le premier protocole, et sont pr\u00e9vus sur le second.<\/p>\n<p><strong>L\u2019actualit\u00e9 nationale<\/strong><\/p>\n<p>Nous poursuivons les \u00e9changes avec les parlementaires, qui relaient nos messages, par voie de questions pos\u00e9es au gouvernement, et de messages adress\u00e9s aux responsables concern\u00e9s. L\u2019id\u00e9e d\u2019une proposition de loi a \u00e9t\u00e9 \u00e9voqu\u00e9e, qui pourrait porter sur la reconnaissance de la forme persistante de Lyme et sur le suivi des patients, semblable dans l\u2019esprit \u00e0 celle promulgu\u00e9e en janvier 2022 pour le Covid long. Cette loi Covid long a permis d\u2019avancer sur la reconnaissance de la situation des patients, c\u2019est une piste \u00e0 laquelle nous n\u2019avions pas pens\u00e9, et sur laquelle nous avons commenc\u00e9 \u00e0 travailler.<\/p>\n<p>Pour l\u2019anecdote, alors que j\u2019\u00e9tais dans le quartier de l\u2019Assembl\u00e9e, j\u2019ai crois\u00e9 S\u00e9bastien Chenu, qui est D\u00e9put\u00e9 (RN) et surtout l\u2019un des Vice-Pr\u00e9sidents de l\u2019Assembl\u00e9e, en charge des groupes d\u2019\u00e9tudes. C\u2019est lui qui a la main sur le nombre des groupes d\u2019\u00e9tudes, nombre ramen\u00e9 de 120 \u00e0 80 pour cette nouvelle mandature, en supprimant notamment le groupe d\u2019\u00e9tudes Lyme, sans aucune discussion ni information. Je lui ai fait part de notre fort m\u00e9contentement, et lui ai propos\u00e9 de faire un point pour exposer nos motifs. Il m\u2019a demand\u00e9 de lui \u00e9crire pour l\u2019organiser, mais sa r\u00e9ponse tarde \u00e0 venir\u2026<\/p>\n<p>Nous avons rencontr\u00e9 des responsables du Minist\u00e8re de la Sant\u00e9, plus exactement de la Direction G\u00e9n\u00e9rale de la Sant\u00e9, \u00e0 notre initiative. Nous leur avons pr\u00e9sent\u00e9 la situation actuelle des malades, issue de l\u2019\u00e9tude que nous vous avons pr\u00e9sent\u00e9e, ainsi que le bilan (malheureusement tr\u00e8s n\u00e9gatif) que nous faisons du Plan Lyme de 2016.<br \/>La discussion a port\u00e9 sur tous les sujets importants : le diagnostic, la prise en charge, le parcours de soins, les aspects sociaux, la formation des m\u00e9decins, la recherche, etc.<br \/>Nous avons propos\u00e9 de mettre en chantier un nouveau Plan Lyme, un \u00ab vrai \u00bb Plan Lyme, vraiment pilot\u00e9 et financ\u00e9, visant \u00e0 prendre en charge r\u00e9ellement tous les patients, et \u00e0 financer les recherches n\u00e9cessaires. Cette proposition a re\u00e7u un \u00e9cho plut\u00f4t favorable, ce qui est encourageant, mais de toute \u00e9vidence il nous faudra d\u2019autres rendez-vous pour avancer plus concr\u00e8tement.<\/p>\n<p>Un conseil de lecture pour compl\u00e9ter l\u2019actualit\u00e9 nationale : le livre de Marie F\u00e9lix \u00ab Lyme, si les malades savaient, si les m\u00e9decins pouvaient \u00bb, qui vient de para\u00eetre aux \u00e9ditions Caban.<br \/>Ce livre est un t\u00e9moignage poignant, mais aussi une formidable enqu\u00eate sur la situation<br \/>absurde de cette maladie, et la situation catastrophique des malades en France. Elle revient sur son errance m\u00e9dicale et sur tous les obstacles qu\u2019elle a d\u00fb affronter pour retrouver la sant\u00e9. Elle relate les \u00e9changes, souvent compliqu\u00e9s, qu\u2019elle a eus avec les soignants qu\u2019elle a crois\u00e9 au long de son parcours, et nous livre un r\u00e9cit digne d\u2019un journaliste d\u2019investigation.<\/p>\n<p><strong>L\u2019actualit\u00e9 (encore bien charg\u00e9e) de France Lyme<\/strong><\/p>\n<p>Nous vous remercions d\u2019avoir \u00e9t\u00e9 nombreux \u00e0 avoir particip\u00e9 au vote de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale Extraordinaire (AGE) du 3 mai. Nous avons \u00e9t\u00e9 tr\u00e8s touch\u00e9s par vos nombreux commentaires d\u2019encouragement. Vos votes ont massivement soutenu le projet de devenir une Association Reconnue d\u2019Utilit\u00e9 Publique (ARUP), et l\u2019adoption des nouveaux Statuts. C\u2019est une \u00e9tape importante pour l\u2019association que nous venons de franchir, nous vous remercions chaleureusement pour votre confiance.<\/p>\n<p>Au nom du Conseil d\u2019Administration, je remercie tous les b\u00e9n\u00e9voles et les adh\u00e9rents qui se sont mobilis\u00e9s au cours du mois de Mai (le mois du \u00ab Lyme Protest \u00bb international), les sections locales qui ont organis\u00e9 des \u00e9v\u00e9nements, et toutes les personnes qui nous ont aid\u00e9 \u00e0 communiquer sur les r\u00e9seaux par le biais des t\u00e9moignages \u00e9crits et vid\u00e9o.<\/p>\n<p>Dans ce cadre, notre webinaire du 16 mai s\u2019annon\u00e7ait bien d\u00e8s le d\u00e9part, avec au programme les docteurs Claire Delval et Richard Horowitz. Mais franchement, il a d\u00e9pass\u00e9 nos attentes, de par la qualit\u00e9 des pr\u00e9sentations et des \u00e9changes.<br \/>Seule (petite) ombre au tableau, nous avons \u00e9t\u00e9 limit\u00e9s par Zoom \u00e0 100 personnes \u00e0 cause d\u2019un bug, et nous savons que beaucoup d\u2019entre vous n\u2019ont pu se connecter, nous en sommes navr\u00e9s. Mais la bonne nouvelle est que le webinaire est d\u00e9j\u00e0 disponible en replay sur notre site.<br \/>En particulier pour voir la pr\u00e9sentation tr\u00e8s int\u00e9ressante du Dr Claire Delval, qui montre tous les aspects de l\u2019infection, des facteurs sous-jacents qui influent sur sa persistance, qu\u2019ils concernent l\u2019hygi\u00e8ne de vie, les toxiques, l\u2019environnement au sens large, etc., et qui dresse une palette compl\u00e8te des traitements possibles.<br \/>Et aussi, bien s\u00fbr, pour partager la vision du Dr Horowitz, grand sp\u00e9cialiste am\u00e9ricain des maladies \u00e0 tique, qui travaille sans cesse \u00e0 l\u2019am\u00e9lioration des protocoles de traitement, et qui pr\u00e9sente ici les r\u00e9sultats convaincants qu\u2019il obtient en 8 semaines avec ses protocoles \u00ab Double Dose Dapsone \u00bb et \u00ab High Dose Dapsone \u00bb.<br \/>Deux patientes, Jeanne et Julie sont venues \u00e9galement apporter des t\u00e9moignages tr\u00e8s touchants, et des messages d\u2019espoir pour les malades.<br \/>Pour notre part, nous y avons pr\u00e9sent\u00e9 le retour d\u2019exp\u00e9rience des malades, le bilan du Plan Lyme 2016, et nos propositions pour un nouveau Plan Lyme.<\/p>\n<p>Nous encha\u00eenons tr\u00e8s bient\u00f4t avec l\u2019Assembl\u00e9e G\u00e9n\u00e9rale Ordinaire (et annuelle), qui se d\u00e9roulera en pr\u00e9sentiel \u00e0 Lyon et en webinaire, le dimanche 11 juin \u00e0 9h30<br \/>Pour rejoindre le webinaire de l\u2019AG : https:\/\/us02web.zoom.us\/j\/84401130161<\/p>\n<p>Si vous souhaitez vous joindre \u00e0 nous sur place \u00e0 Lyon (h\u00f4tel Campanile La Part Dieu), vous \u00eates les (tr\u00e8s) bienvenus, vous pouvez nous avertir de votre venue.<\/p>\n<p>A l&rsquo;occasion de cette assembl\u00e9e g\u00e9n\u00e9rale \u00e0 Lyon et de la pr\u00e9sence d&rsquo;une partie du conseil d&rsquo;administration, nous vous proposons de se rencontrer :<br \/>&#8211; Samedi 10 juin \u00e0 19h30 dans une brasserie dans Lyon 2. (attention, ce n&rsquo;est plus \u00e0 la brasserie Georges). Il reste 3 places.<br \/>&#8211; Dimanche 11 juin \u00e0 12h au restaurant Campanile Lyon Gare Part Dieu. Il reste 5 places. Brunch \u00ab\u00a0Buffet \u00e0 volont\u00e9\u00a0\u00bb : 25.00\u20ac\/personne.<br \/>Pour ces deux rencontres, merci de vous inscrire avant le mercredi 7 juin.<\/p>\n<p>Enfin, comme tous les mois, j\u2019adresse un grand merci \u00e0 toutes les \u00e9quipes de b\u00e9n\u00e9voles impliqu\u00e9es sur le terrain et dans les services de France Lyme, en particulier en ce mois de mai qui a \u00e9t\u00e9 particuli\u00e8rement charg\u00e9.<\/p>\n<p>Un grand merci aussi \u00e0 Nathalie pour ses VisioLyme, ces rendez-vous d\u2019\u00e9changes en visio entre malades, qu\u2019elle a multipli\u00e9 ce mois-ci. N\u2019h\u00e9sitez pas \u00e0 vous y inscrire, c\u2019est une mani\u00e8re simple et efficace pour partager des infos et \u00e9changer des retours d\u2019exp\u00e9rience sur la maladie.<\/p>\n<p>Merci pour votre soutien.<br \/>Amicalement,<\/p>\n<p>Fr\u00e9d\u00e9ric MAIRE<br \/>Pr\u00e9sident de France Lyme<\/p>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-1024x1024.jpg\" alt=\"\" class=\"wp-image-15197\" srcset=\"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-1024x1024.jpg 1024w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-300x300.jpg 300w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-150x150.jpg 150w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-768x768.jpg 768w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-90x90.jpg 90w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite-75x75.jpg 75w, https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.helloasso.com\/associations\/association-france-lyme\/adhesions\/adhesion-membre-ami\" target=\"_blank\" rel=\"noreferrer noopener\">Devenez membre ami pour recevoir les actualit\u00e9s<\/a><\/p>\n<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":17,"featured_media":15197,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[288],"tags":[],"class_list":["post-15220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editoriaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9ditorial de juin 2023 - Association France Lyme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9ditorial de juin 2023 - Association France Lyme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Association France Lyme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/france.lyme\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-01T16:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T21:56:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@francelyme\" \/>\n<meta name=\"twitter:site\" content=\"@francelyme\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00c9ditorial de juin 2023\",\"datePublished\":\"2023-06-01T16:34:00+00:00\",\"dateModified\":\"2025-11-29T21:56:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/\"},\"wordCount\":1646,\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Editorial-Carre-Suivez-lactualite.jpg\",\"articleSection\":[\"Editoriaux\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/\",\"name\":\"\u00c9ditorial de juin 2023 - Association France Lyme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Editorial-Carre-Suivez-lactualite.jpg\",\"datePublished\":\"2023-06-01T16:34:00+00:00\",\"dateModified\":\"2025-11-29T21:56:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Editorial-Carre-Suivez-lactualite.jpg\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Editorial-Carre-Suivez-lactualite.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/editorial-de-juin-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9ditorial de juin 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"name\":\"Association France Lyme\",\"description\":\"Association de lutte contre les maladies vectorielles \u00e0 tiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\",\"name\":\"France Lyme\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"width\":180,\"height\":180,\"caption\":\"France Lyme\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/france.lyme\",\"https:\\\/\\\/x.com\\\/francelyme\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClMCGl3dvkz0iAgXFR1NH1A\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9ditorial de juin 2023 - Association France Lyme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9ditorial de juin 2023 - Association France Lyme","og_url":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/","og_site_name":"Association France Lyme","article_publisher":"https:\/\/www.facebook.com\/france.lyme","article_published_time":"2023-06-01T16:34:00+00:00","article_modified_time":"2025-11-29T21:56:56+00:00","og_image":[{"width":1080,"height":1080,"url":"http:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@francelyme","twitter_site":"@francelyme","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#article","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/"},"author":{"name":"","@id":""},"headline":"\u00c9ditorial de juin 2023","datePublished":"2023-06-01T16:34:00+00:00","dateModified":"2025-11-29T21:56:56+00:00","mainEntityOfPage":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/"},"wordCount":1646,"publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"image":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg","articleSection":["Editoriaux"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/","url":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/","name":"\u00c9ditorial de juin 2023 - Association France Lyme","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#primaryimage"},"image":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg","datePublished":"2023-06-01T16:34:00+00:00","dateModified":"2025-11-29T21:56:56+00:00","breadcrumb":{"@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#primaryimage","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2023\/09\/Editorial-Carre-Suivez-lactualite.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/francelyme.fr\/site\/editorial-de-juin-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francelyme.fr\/site\/"},{"@type":"ListItem","position":2,"name":"\u00c9ditorial de juin 2023"}]},{"@type":"WebSite","@id":"https:\/\/francelyme.fr\/site\/#website","url":"https:\/\/francelyme.fr\/site\/","name":"Association France Lyme","description":"Association de lutte contre les maladies vectorielles \u00e0 tiques","publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francelyme.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/francelyme.fr\/site\/#organization","name":"France Lyme","url":"https:\/\/francelyme.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","width":180,"height":180,"caption":"France Lyme"},"image":{"@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/france.lyme","https:\/\/x.com\/francelyme","https:\/\/www.youtube.com\/channel\/UClMCGl3dvkz0iAgXFR1NH1A"]},{"@type":"Person","@id":"","url":"https:\/\/francelyme.fr\/site\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/15220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/comments?post=15220"}],"version-history":[{"count":2,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/15220\/revisions"}],"predecessor-version":[{"id":19104,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/15220\/revisions\/19104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media\/15197"}],"wp:attachment":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media?parent=15220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/categories?post=15220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/tags?post=15220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}