{"id":17408,"date":"2025-02-01T22:31:20","date_gmt":"2025-02-01T21:31:20","guid":{"rendered":"https:\/\/francelyme.fr\/site\/?p=17408"},"modified":"2025-02-02T22:31:51","modified_gmt":"2025-02-02T21:31:51","slug":"revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme","status":"publish","type":"post","link":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/","title":{"rendered":"Revue de la controverse sur l&rsquo;inefficacit\u00e9 des tests biologiques et preuve de l&rsquo;existence d&rsquo;une forme chronique de Lyme"},"content":{"rendered":"<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n<div id=\"fb-root\"><\/div>\n\n<p>Dans cet article de 19 pages publi\u00e9 le 30 d\u00e9cembre 2024 dans la revue Fortune Journals, le Dr Lacout et le Pr Perronne font le point sur la controverse concernant le diagnostic et le traitement de la maladie de Lyme. L\u2019article met en \u00e9vidence l\u2019inefficacit\u00e9 des tests biologiques (ELISA et Western Blot), souvent n\u00e9gatifs chez des patients pourtant atteints. Les auteurs citent les preuves scientifiques qui attestent la persistance de Borrelia et des co-infections, qui selon eux n\u00e9cessitent des traitements prolong\u00e9s. Pour ces m\u00e9decins, un traitement antibiotique prolong\u00e9, parfois associ\u00e9 \u00e0 des antiparasitaires, est souvent n\u00e9cessaire en raison des rechutes fr\u00e9quentes. L\u2019article \u00e9voque aussi des aspects politico-militaires expliquant possiblement le d\u00e9ni officiel de cette maladie.<\/p>\n\n\n\n<p>Quelques extraits significatifs du texte&nbsp;:<\/p>\n\n\n\n<p><em>\u00ab..&nbsp;Les tests diagnostiques ELISA et Western blot cens\u00e9s pr\u00e9senter, d\u2019apr\u00e8s certains experts, une sensibilit\u00e9 de presque 100 %, sont en fait souvent n\u00e9gatifs chez de nombreux patients ayant une authentique maladie de Lyme. Ces tests sont mal calibr\u00e9s, de m\u00e9diocre qualit\u00e9 avec un seuil de positivit\u00e9 des anticorps d\u00e9fini de mani\u00e8re arbitraire pour ne jamais trouver plus de 5% de patients avec un test positif dans chaque r\u00e9gion..&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00ab.. Il existe une controverse sur l\u2019existence de la forme chronique. Cependant, une chronicit\u00e9 est observ\u00e9e chez de nombreux patients, et les m\u00e9canismes de persistance de Borrelia sont tr\u00e8s bien document\u00e9s dans les publications scientifiques. R\u00e9cemment, en 2018, la Haute Autorit\u00e9 de Sant\u00e9 a d\u00e9fini le SPPT (Syndrome persistant polymorphe apr\u00e8s possible piq\u00fbre de tique), qui permet d\u2019effectuer un traitement antibiotique empirique d\u2019\u00e9preuve devant une maladie persistante mal expliqu\u00e9e par les investigations habituelles, m\u00eame en cas de s\u00e9rologie Lyme n\u00e9gative..&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00ab&nbsp;.. La maladie de Lyme, par ailleurs, s\u2019associe fr\u00e9quemment \u00e0 de nombreuses autres infections inapparentes, appel\u00e9es crypto-infections, qu\u2019elles soient parasitaires, bact\u00e9riennes, virales, ou m\u00eame fungiques. Le traitement doit \u00eatre efficace sur Borrelia et les autres co-infections. Un traitement antibiotique long de plusieurs semaines ou mois, souvent associ\u00e9 \u00e0 des m\u00e9dicaments anti-parasitaires, peut \u00eatre n\u00e9cessaire ..&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00ab .. Nier les r\u00e9alit\u00e9s scientifiques publi\u00e9es d\u00e9crites dans cet article a pour cons\u00e9quence des centaines de milliers de malades en errance souffrant de sympt\u00f4mes invalidants, non soign\u00e9s, alors qu\u2019un traitement anti-infectieux appropri\u00e9 et de co\u00fbt modique permet une r\u00e9mission dans de tr\u00e8s nombreux cas..&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p>Enfin, je vous recommande de consulter la liste de publications abondante sur laquelle s\u2019appuient les auteurs, qui comporte 174 r\u00e9f\u00e9rences au total, dont certaines sont peu connues.<\/p>\n\n\n\n<p><em>Pour en savoir plus, l\u2019article publi\u00e9 dans Fortune Journals le 30-12-2024\u00a0:<\/em><\/p>\n\n\n\n<p><a href=\"https:\/\/www.fortunejournals.com\/articles\/maladie-de-lyme-tests-et-traitement--le-point-sur-la-controverse.pdf\"><em>Fortune Journals &#8211; maladie de lyme tests et traitement le point sur la controverse<\/em><\/a><em><\/em><\/p>\n<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":17,"featured_media":17441,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287],"tags":[],"class_list":["post-17408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revue de la controverse sur l&#039;inefficacit\u00e9 des tests biologiques et preuve de l&#039;existence d&#039;une forme chronique de Lyme - Association France Lyme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revue de la controverse sur l&#039;inefficacit\u00e9 des tests biologiques et preuve de l&#039;existence d&#039;une forme chronique de Lyme - Association France Lyme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/\" \/>\n<meta property=\"og:site_name\" content=\"Association France Lyme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/france.lyme\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-01T21:31:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-02T21:31:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@francelyme\" \/>\n<meta name=\"twitter:site\" content=\"@francelyme\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Revue de la controverse sur l&rsquo;inefficacit\u00e9 des tests biologiques et preuve de l&rsquo;existence d&rsquo;une forme chronique de Lyme\",\"datePublished\":\"2025-02-01T21:31:20+00:00\",\"dateModified\":\"2025-02-02T21:31:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/\",\"name\":\"Revue de la controverse sur l'inefficacit\u00e9 des tests biologiques et preuve de l'existence d'une forme chronique de Lyme - Association France Lyme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg\",\"datePublished\":\"2025-02-01T21:31:20+00:00\",\"dateModified\":\"2025-02-02T21:31:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revue de la controverse sur l&#8217;inefficacit\u00e9 des tests biologiques et preuve de l&#8217;existence d&#8217;une forme chronique de Lyme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"name\":\"Association France Lyme\",\"description\":\"Association de lutte contre les maladies vectorielles \u00e0 tiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\",\"name\":\"France Lyme\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"width\":180,\"height\":180,\"caption\":\"France Lyme\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/france.lyme\",\"https:\\\/\\\/x.com\\\/francelyme\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClMCGl3dvkz0iAgXFR1NH1A\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revue de la controverse sur l'inefficacit\u00e9 des tests biologiques et preuve de l'existence d'une forme chronique de Lyme - Association France Lyme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/","og_locale":"fr_FR","og_type":"article","og_title":"Revue de la controverse sur l'inefficacit\u00e9 des tests biologiques et preuve de l'existence d'une forme chronique de Lyme - Association France Lyme","og_url":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/","og_site_name":"Association France Lyme","article_publisher":"https:\/\/www.facebook.com\/france.lyme","article_published_time":"2025-02-01T21:31:20+00:00","article_modified_time":"2025-02-02T21:31:51+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@francelyme","twitter_site":"@francelyme","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#article","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/"},"author":{"name":"","@id":""},"headline":"Revue de la controverse sur l&rsquo;inefficacit\u00e9 des tests biologiques et preuve de l&rsquo;existence d&rsquo;une forme chronique de Lyme","datePublished":"2025-02-01T21:31:20+00:00","dateModified":"2025-02-02T21:31:51+00:00","mainEntityOfPage":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/"},"wordCount":492,"publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"image":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/","url":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/","name":"Revue de la controverse sur l'inefficacit\u00e9 des tests biologiques et preuve de l'existence d'une forme chronique de Lyme - Association France Lyme","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#primaryimage"},"image":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg","datePublished":"2025-02-01T21:31:20+00:00","dateModified":"2025-02-02T21:31:51+00:00","breadcrumb":{"@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#primaryimage","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2025\/02\/revue-Fortune-Journals-le-Dr-Lacout-et-le-Pr-Perronne.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/francelyme.fr\/site\/revue-de-la-controverse-sur-linefficacite-des-tests-biologiques-et-preuve-de-lexistence-dune-forme-chronique-de-lyme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francelyme.fr\/site\/"},{"@type":"ListItem","position":2,"name":"Revue de la controverse sur l&#8217;inefficacit\u00e9 des tests biologiques et preuve de l&#8217;existence d&#8217;une forme chronique de Lyme"}]},{"@type":"WebSite","@id":"https:\/\/francelyme.fr\/site\/#website","url":"https:\/\/francelyme.fr\/site\/","name":"Association France Lyme","description":"Association de lutte contre les maladies vectorielles \u00e0 tiques","publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francelyme.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/francelyme.fr\/site\/#organization","name":"France Lyme","url":"https:\/\/francelyme.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","width":180,"height":180,"caption":"France Lyme"},"image":{"@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/france.lyme","https:\/\/x.com\/francelyme","https:\/\/www.youtube.com\/channel\/UClMCGl3dvkz0iAgXFR1NH1A"]},{"@type":"Person","@id":"","url":"https:\/\/francelyme.fr\/site\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/17408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/comments?post=17408"}],"version-history":[{"count":2,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/17408\/revisions"}],"predecessor-version":[{"id":17442,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/17408\/revisions\/17442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media\/17441"}],"wp:attachment":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media?parent=17408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/categories?post=17408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/tags?post=17408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}