{"id":2071,"date":"2013-09-10T14:51:07","date_gmt":"2013-09-10T12:51:07","guid":{"rendered":"http:\/\/francelyme.fr\/?p=2071"},"modified":"2013-09-10T14:51:07","modified_gmt":"2013-09-10T12:51:07","slug":"enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france","status":"publish","type":"post","link":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/","title":{"rendered":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France"},"content":{"rendered":"<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n<div id=\"fb-root\"><\/div>\n<p>\t\t\t\tParticipez \u00e0 l\u2019enqu\u00eate publique qui nous a \u00e9t\u00e9 transmise :<\/p>\n<p>La menace des tiques est sous-estim\u00e9e en France comme en Belgique<\/p>\n<blockquote>\n<div>Un millier de cas de Borr\u00e9liose de Lyme sont recens\u00e9s annuellement en Belgique contre 22000 cas aux Pays-Bas, un pays proche et aux conditions environnementales similaires. Les chiffres belges sont largement sous-estim\u00e9s. Une \u00e9tude r\u00e9cente permet d\u2019estimer le nombre de cas \u00e0 15000 par an et un article r\u00e9cent d\u00e9montre que les tiques vectrices se trouvent un peu partout sur le territoire belge, sont parfois tr\u00e8s abondantes localement et contiennent de nombreux pathog\u00e8nes autres que la maladie de Lyme. Afin d\u2019identifier les zones \u00e0 risque et les sympt\u00f4mes les plus fr\u00e9quents, nous demandons \u00e0 la population d\u2019indiquer, d\u00e8s qu\u2019elle le peut, le lieu de morsure par une tique et les sympt\u00f4mes sur le site de l\u2019enqu\u00eate <a href=\"http:\/\/www.tekentiques.net\">http:\/\/www.tekentiques.net<\/a>. 1500 belges ont d\u00e9j\u00e0 r\u00e9pondu en 1 mois et l\u2019enqu\u00eate est maintenant \u00e9galement ouverte \u00e0 la France. Les r\u00e9sultats seront pr\u00e9sent\u00e9s r\u00e9guli\u00e8rement sur le site et ce d\u00e8s le 15 septembre.<br \/>\nVal\u00e9rie Obsomer \u2013 Earth and Life Institute,Universit\u00e9 catholique de Louvain, Belgique<\/div>\n<\/blockquote>\n<div><strong>Les liens :<\/strong><span style=\"text-decoration: underline\"><a href=\"http:\/\/www.parasitesandvectors.com\/content\/6\/1\/190\">L\u2019article scientifique publi\u00e9<\/a><\/span> (sur un site open source sp\u00e9cialis\u00e9)<br \/>\nComprend trois cartes qui d\u00e9crivent la distribution des esp\u00e8ces, les variation d\u2019abondance de la tique vectrice principale de Lyme et une carte des pathog\u00e8nes trouv\u00e9es dans les tiques de Belgique, mais \u00e9galement en suppl\u00e9ment notamment\u00a0 la liste des microorganis<\/div>\n<div><a title=\"Site enqu\u00eate Lyme Belgique\" href=\"http:\/\/www.tekentiques.net\">Le site pour l\u2019enqu\u00eate<\/a><span style=\"text-decoration: underline\">Article de presse original dans avenir.net reprit ensuite par Belga :<\/span><br \/>\nONLINE : Lavenir.net \u2013 3 articles ( dans la version papier il y avait aussi la carte d\u2019abondance)<br \/>\nhttp:\/\/www.lavenir.net\/article\/detail.aspx?articleid=dmf20130724_00339230<br \/>\nhttp:\/\/www.lavenir.net\/article\/detail.aspx?articleid=DMF20130724_00339418<br \/>\nhttp:\/\/www.lavenir.net\/article\/detail.aspx?articleid=DMF20130724_00339459[u]RTL TVI Vid\u00e9o Reportage original \u00e0 la t\u00e9l\u00e9vision le 28\/07\/2013 : RTL TVI <a href=\"http:\/\/www.rtl.be\/videos\/video\/452707.aspx?CategoryID=2907\">Vid\u00e9o<\/a> <a href=\"http:\/\/www.rtl.be\/info\/belgique\/societe\/1020244\/la-menace-des-tiques-de-nombreux-cas-de-maladies-en-belgique\">Texte<\/a><\/p>\n<\/div>\n<div class=\"like-button\" style=\"float: right; clear: both; text-align: right; width = 100%;\">\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/\" data-layout=\"box_count\" data-action=\"like\" data-show-faces=\"false\" data-size=\"large\" data-width=\"450\" data-share=\"1\" ><\/div><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2080,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,34,104],"tags":[137,139,122],"class_list":["post-2071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-belgique","category-medias","category-recherche","tag-belgique","tag-enquete","tag-epidemiologie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Association France Lyme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/france.lyme\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-10T12:51:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AdminFL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@francelyme\" \/>\n<meta name=\"twitter:site\" content=\"@francelyme\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AdminFL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/\"},\"author\":{\"name\":\"AdminFL\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/person\\\/1a2c2689f69ecd6062cfac7d4b12f265\"},\"headline\":\"Enqu\u00eate sur Lyme et les tiques en Belgique et en France\",\"datePublished\":\"2013-09-10T12:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/\"},\"wordCount\":351,\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/enquete.jpg\",\"keywords\":[\"Belgique\",\"Enqu\u00eate\",\"Epid\u00e9miologie\"],\"articleSection\":[\"Belgique\",\"M\u00e9dias\",\"Recherche\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/\",\"name\":\"Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/enquete.jpg\",\"datePublished\":\"2013-09-10T12:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/enquete.jpg\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/enquete.jpg\",\"width\":150,\"height\":150,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enqu\u00eate sur Lyme et les tiques en Belgique et en France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"name\":\"Association France Lyme\",\"description\":\"Association de lutte contre les maladies vectorielles \u00e0 tiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#organization\",\"name\":\"France Lyme\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"contentUrl\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/francelyme-site.gif\",\"width\":180,\"height\":180,\"caption\":\"France Lyme\"},\"image\":{\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/france.lyme\",\"https:\\\/\\\/x.com\\\/francelyme\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClMCGl3dvkz0iAgXFR1NH1A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/#\\\/schema\\\/person\\\/1a2c2689f69ecd6062cfac7d4b12f265\",\"name\":\"AdminFL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g\",\"caption\":\"AdminFL\"},\"url\":\"https:\\\/\\\/francelyme.fr\\\/site\\\/author\\\/fralymadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme","og_url":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/","og_site_name":"Association France Lyme","article_publisher":"https:\/\/www.facebook.com\/france.lyme","article_published_time":"2013-09-10T12:51:07+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg","type":"image\/jpeg"}],"author":"AdminFL","twitter_card":"summary_large_image","twitter_creator":"@francelyme","twitter_site":"@francelyme","twitter_misc":{"\u00c9crit par":"AdminFL","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#article","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/"},"author":{"name":"AdminFL","@id":"https:\/\/francelyme.fr\/site\/#\/schema\/person\/1a2c2689f69ecd6062cfac7d4b12f265"},"headline":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France","datePublished":"2013-09-10T12:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/"},"wordCount":351,"publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"image":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg","keywords":["Belgique","Enqu\u00eate","Epid\u00e9miologie"],"articleSection":["Belgique","M\u00e9dias","Recherche"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/","url":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/","name":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France - Association France Lyme","isPartOf":{"@id":"https:\/\/francelyme.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#primaryimage"},"image":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#primaryimage"},"thumbnailUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg","datePublished":"2013-09-10T12:51:07+00:00","breadcrumb":{"@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#primaryimage","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2013\/09\/enquete.jpg","width":150,"height":150,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/francelyme.fr\/site\/enquete-sur-lyme-et-les-tiques-en-belgique-et-en-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francelyme.fr\/site\/"},{"@type":"ListItem","position":2,"name":"Enqu\u00eate sur Lyme et les tiques en Belgique et en France"}]},{"@type":"WebSite","@id":"https:\/\/francelyme.fr\/site\/#website","url":"https:\/\/francelyme.fr\/site\/","name":"Association France Lyme","description":"Association de lutte contre les maladies vectorielles \u00e0 tiques","publisher":{"@id":"https:\/\/francelyme.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francelyme.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/francelyme.fr\/site\/#organization","name":"France Lyme","url":"https:\/\/francelyme.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/","url":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","contentUrl":"https:\/\/francelyme.fr\/site\/wp-content\/uploads\/2019\/05\/francelyme-site.gif","width":180,"height":180,"caption":"France Lyme"},"image":{"@id":"https:\/\/francelyme.fr\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/france.lyme","https:\/\/x.com\/francelyme","https:\/\/www.youtube.com\/channel\/UClMCGl3dvkz0iAgXFR1NH1A"]},{"@type":"Person","@id":"https:\/\/francelyme.fr\/site\/#\/schema\/person\/1a2c2689f69ecd6062cfac7d4b12f265","name":"AdminFL","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4920874779d1914d5cba6d6dc7a2f20c832bb43238e659994a133a63cb03c29e?s=96&d=mm&r=g","caption":"AdminFL"},"url":"https:\/\/francelyme.fr\/site\/author\/fralymadm\/"}]}},"_links":{"self":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/2071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/comments?post=2071"}],"version-history":[{"count":0,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/posts\/2071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media\/2080"}],"wp:attachment":[{"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/media?parent=2071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/categories?post=2071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francelyme.fr\/site\/wp-json\/wp\/v2\/tags?post=2071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}